{"id":4,"count":2,"description":"","link":"https:\/\/demo.17thavenuedesigns.com\/adeline\/category\/career\/","name":"Career","slug":"career","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.17thavenuedesigns.com\/adeline\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.17thavenuedesigns.com\/adeline\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.17thavenuedesigns.com\/adeline\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.17thavenuedesigns.com\/adeline\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}